{"id":9920,"date":"2026-05-13T16:34:17","date_gmt":"2026-05-13T16:34:17","guid":{"rendered":"https:\/\/friburgonoticias.com.br\/temp\/2026\/05\/13\/camara-pelo-brasil-promove-debates-em-capitais-sobre-escala-6x1-misoginia-e-mei-noticias\/"},"modified":"2026-05-13T16:34:17","modified_gmt":"2026-05-13T16:34:17","slug":"camara-pelo-brasil-promove-debates-em-capitais-sobre-escala-6x1-misoginia-e-mei-noticias","status":"publish","type":"post","link":"https:\/\/friburgonoticias.com.br\/temp\/2026\/05\/13\/camara-pelo-brasil-promove-debates-em-capitais-sobre-escala-6x1-misoginia-e-mei-noticias\/","title":{"rendered":"&#8216;C\u00e2mara pelo Brasil&#8217; promove debates em capitais sobre escala 6&#215;1, misoginia e MEI &#8211; Not\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n                                            13\/05\/2026 &#8211; 12:51 \u00a0\n                                        <\/p>\n<p>                O <a href=\"https:\/\/www.camara.leg.br\/noticias\/1181328-hugo-motta-cria-programa-camara-pelo-brasil-para-ampliar-o-dialogo-com-a-sociedade\/\">programa C\u00e2mara pelo Brasil<\/a> continuar\u00e1 percorrendo capitais brasileiras neste m\u00eas de maio para debater propostas em tramita\u00e7\u00e3o na C\u00e2mara dos Deputados relacionadas \u00e0 redu\u00e7\u00e3o da jornada de trabalho e ao fim da escala 6&#215;1.<br \/>\n                A iniciativa prev\u00ea semin\u00e1rios regionais sobre as propostas de emenda \u00e0 Constitui\u00e7\u00e3o (PECs) <a href=\"https:\/\/www.camara.leg.br\/noticias\/632530-pec-reduz-jornada-semanal-de-trabalho-de-44-para-36-horas\">221\/19<\/a> e <a href=\"https:\/\/www.camara.leg.br\/noticias\/1136412-pec-preve-a-adocao-da-jornada-de-quatro-dias-de-trabalho-para-todos-os-trabalhadores-brasileiros\">8\/25<\/a> e contar\u00e1 com a participa\u00e7\u00e3o de integrantes da <a href=\"https:\/\/www.camara.leg.br\/noticias\/1267523-comissao-especial-que-vai-analisar-o-fim-da-escala-6x1-comeca-a-funcionar\/\">comiss\u00e3o especial que foi instalada no final de abril<\/a>.<br \/>\n                Na semana passada, <a href=\"https:\/\/www.camara.leg.br\/noticias\/1270261-em-debate-na-paraiba,-trabalhadores-defendem-fim-da-escala-6x1-e-empresarios-pregam-dialogo\">o encontro foi realizado em Jo\u00e3o Pessoa (PB)<\/a>.<br \/>\n                O programa tamb\u00e9m vai discutir o combate \u00e0 misoginia (<a href=\"https:\/\/www.camara.leg.br\/noticias\/1266776-projeto-equipara-misoginia-ao-crime-de-racismo-e-torna-a-pratica-inafiancavel-e-imprescritivel\/\">PL 896\/23<\/a>) e mudan\u00e7as (<a href=\"https:\/\/www.camara.leg.br\/noticias\/845632-projeto-aumenta-limite-de-faturamento-para-microempreendedor-individual\">PLP 108\/21<\/a>) nas regras do microempreendedor individual (MEI).<br \/>\n                <strong>Programa\u00e7\u00e3o sobre fim da escala 6&#215;1<\/strong><br \/>Nesta quinta-feira (14), em S\u00e3o Paulo, ser\u00e1 realizado semin\u00e1rio, \u00e0s 9h30, no Pal\u00e1cio do Trabalhador, sede da For\u00e7a Sindical.<br \/>\n                Est\u00e3o confirmados o ministro do Trabalho, Luiz Marinho; o presidente da For\u00e7a Sindical, Miguel Torres; o coordenador do programa C\u00e2mara pelo Brasil, deputado Da Vitoria (PP-ES); o presidente da comiss\u00e3o especial sobre o fim da escala 6X1, deputado Alencar Santana (PT-SP); o relator do texto, deputado Leo Prates (Republicanos-BA); e outros dois integrantes da comiss\u00e3o, os deputados Carlos Zarattini (PT-SP) e Alfredinho (PT-SP).<br \/>\n                No dia seguinte (15), o debate ser\u00e1 realizado no Rio Grande do Sul, na Superintend\u00eancia Regional de Administra\u00e7\u00e3o, na Cidade Baixa, em Porto Alegre, \u00e0s 9h30.<br \/>\n                Participar\u00e3o do encontro: o presidente e o relator da comiss\u00e3o especial; a 1\u00aa vice-presidente da comiss\u00e3o, deputada Daiana Santos (PCdoB-RS); al\u00e9m das deputadas Fernanda Melchionna (Psol-RS) e Maria do Ros\u00e1rio (PT-RS), integrantes do colegiado. Tamb\u00e9m estar\u00e1 presente o l\u00edder do governo na C\u00e2mara dos Deputados, deputado Paulo Pimenta (PT-RS).<br \/>\n                No s\u00e1bado (16), o encontro ocorrer\u00e1 no Maranh\u00e3o, \u00e0s 10 horas, na C\u00e2mara Municipal de S\u00e3o Lu\u00eds. Tamb\u00e9m contar\u00e1 com a presen\u00e7a do presidente e do relator da comiss\u00e3o especial; do coordenador do semin\u00e1rio e integrante da comiss\u00e3o, deputado Rubens Pereira J\u00fanior (PT-MA); e do deputado Duarte Jr. (Avante-MA), membro do colegiado.<br \/>\n                J\u00e1 Belo Horizonte (MG) receber\u00e1 o semin\u00e1rio em 21 de maio, \u00e0s 10 horas, na Assembleia Legislativa de Minas Gerais.<br \/>\n                Manaus (AM) tamb\u00e9m estar\u00e1 na programa\u00e7\u00e3o, no dia 22 de maio, \u00e0s 10 horas, na Assembleia Legislativa do Amazonas.<br \/>\n                <strong>Propostas<\/strong><br \/>Os encontros v\u00e3o discutir a PEC 221\/19, de autoria do deputado Reginaldo Lopes (PT-MG), que prev\u00ea a redu\u00e7\u00e3o gradual da jornada semanal de trabalho de 44 para 36 horas em um prazo de dez anos.<br \/>\n                Tamb\u00e9m ser\u00e1 debatida a PEC 8\/25, apresentada pela deputada Erika Hilton (Psol-SP), que prop\u00f5e uma jornada de quatro dias de trabalho por semana, limitada a 36 horas semanais.<br \/>\n                As propostas avan\u00e7aram recentemente na C\u00e2mara. Em abril, a <a href=\"https:\/\/www.camara.leg.br\/noticias\/1265049-comissao-aprova-admissibilidade-de-propostas-que-acabam-com-a-escala-6x1\/\">Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania aprovou a admissibilidade dos textos<\/a>, que agora s\u00e3o analisados por <a href=\"https:\/\/www.camara.leg.br\/noticias\/1266146-motta-cria-comissao-especial-para-analisar-fim-da-escala-6x1\/\">comiss\u00e3o especial criada pelo presidente da C\u00e2mara<\/a>, Hugo Motta.<br \/>\n                <strong>Misoginia<\/strong><br \/>Al\u00e9m do debate sobre a jornada de trabalho, o programa C\u00e2mara pelo Brasil tamb\u00e9m vai promover, em 29 de maio, \u00e0s 18 horas, em S\u00e3o Paulo, uma discuss\u00e3o sobre o Projeto de Lei 896\/23, do Senado, conhecido como PL da Misoginia.<br \/>\n                A proposta equipara a misoginia \u2013 caracterizada pelo \u00f3dio ou avers\u00e3o \u00e0s mulheres \u2013 ao crime de racismo, tornando a pr\u00e1tica inafian\u00e7\u00e1vel e imprescrit\u00edvel, com pena de <span id=\"4303\" class=\"termoGlossario\" title=\"A reclus\u00e3o \u00e9 a mais severa entre as penas privativas de liberdade. Destina-se a crimes dolosos (com inten\u00e7\u00e3o).\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">reclus\u00e3o<\/span> de dois a cinco anos.<br \/>\n                O encontro contar\u00e1 com a participa\u00e7\u00e3o da deputada Tabata Amaral (PSB-SP), coordenadora do grupo de trabalho respons\u00e1vel pela proposta.<br \/>\n                Segundo a parlamentar, o texto poder\u00e1 ser votado pelo Plen\u00e1rio da C\u00e2mara ainda neste semestre.<br \/>\n                <strong>MEI<\/strong><br \/>A programa\u00e7\u00e3o inclui ainda debate sobre o novo enquadramento do microempreendedor individual, previsto no PLP 108\/21. O tema ser\u00e1 discutido em 1\u00ba de junho.<br \/>\n                A proposta j\u00e1 \u00e9 analisada por comiss\u00e3o especial presidida pela deputada Any Ortiz (PP-RS), sob relatoria do deputado Jorge Goetten (Republicanos-SC).<br \/>\n                <a href=\"https:\/\/www.camara.leg.br\/noticias\/1267536-comissao-especial-sobre-novo-teto-para-mei-e-instalada-na-camara\">O colegiado foi instalado recentemente na C\u00e2mara dos Deputados<\/a> e deve discutir altera\u00e7\u00f5es nas regras de faturamento e enquadramento dos MEIs.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 Regina C\u00e9li Assump\u00e7\u00e3o<br \/>Edi\u00e7\u00e3o \u2013 Marcelo Oliveira<\/p>\n<\/p><\/div>\n<p><\/a><\/p>\n<p>Fonte: www.camara.leg.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13\/05\/2026 &#8211; 12:51 \u00a0 O programa C\u00e2mara pelo Brasil continuar\u00e1 percorrendo capitais brasileiras neste m\u00eas de maio para debater propostas em tramita\u00e7\u00e3o na C\u00e2mara dos Deputados relacionadas \u00e0 redu\u00e7\u00e3o da jornada de trabalho e ao fim da escala 6&#215;1. A iniciativa prev\u00ea semin\u00e1rios regionais sobre as propostas de emenda \u00e0 Constitui\u00e7\u00e3o (PECs) 221\/19 e 8\/25 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"fifu_image_url":"https:\/\/www.camara.leg.br\/midias\/image\/2026\/05\/camara-pelo-brasil-768x538.jpg","fifu_image_alt":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[107],"tags":[],"class_list":{"0":"post-9920","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.camara.leg.br\/midias\/image\/2026\/05\/camara-pelo-brasil-768x538.jpg?fit=%2C&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/posts\/9920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/comments?post=9920"}],"version-history":[{"count":0,"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/posts\/9920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/media\/9921"}],"wp:attachment":[{"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/media?parent=9920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/categories?post=9920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/friburgonoticias.com.br\/temp\/wp-json\/wp\/v2\/tags?post=9920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}